{"id":2803,"date":"2025-10-27T20:43:10","date_gmt":"2025-10-27T23:43:10","guid":{"rendered":"https:\/\/brasil.wordcamp.org\/2025\/?post_type=wcb_session&#038;p=2803"},"modified":"2025-11-27T19:55:23","modified_gmt":"2025-11-27T22:55:23","slug":"ameacas-em-wordpress-prevencao-e-resposta","status":"publish","type":"wcb_session","link":"https:\/\/brasil.wordcamp.org\/2025\/session\/ameacas-em-wordpress-prevencao-e-resposta\/","title":{"rendered":"Cen\u00e1rio de amea\u00e7as 2025 \u2013 Preven\u00e7\u00e3o, Recupera\u00e7\u00e3o e Previs\u00f5es para 2026"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A palestra \u00e9 o resultado do trabalho executado em an\u00e1lise de amea\u00e7as e estudo do cen\u00e1rio atual baseado na coleta de threat intel que desenvolvo na Automattic. Irei apresentar rapidamente o cen\u00e1rio atual, casos reais, formas de precau\u00e7\u00e3o e de resposta. Al\u00e9m de apresentar ferramentas para auxiliar em an\u00e1lise de artefatos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A palestra \u00e9 o resultado do trabalho executado em an\u00e1lise de amea\u00e7as e estudo do cen\u00e1rio atual baseado na coleta de threat intel que desenvolvo na Automattic. Irei apresentar rapidamente o cen\u00e1rio atual, casos reais, formas de precau\u00e7\u00e3o e de resposta. Al\u00e9m de apresentar ferramentas para auxiliar em an\u00e1lise de artefatos.<\/p>\n","protected":false},"author":18232071,"featured_media":0,"template":"","meta":{"_crdt_document":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_post_was_ever_published":false,"_wcpt_session_time":1764439200,"_wcpt_session_duration":2400,"_wcpt_session_type":"session","_wcpt_session_slides":"","_wcpt_session_video":"","_wcpt_speaker_id":[2723],"footnotes":""},"session_track":[35],"session_category":[39],"class_list":["post-2803","wcb_session","type-wcb_session","status-publish","hentry","wcb_track-sala-2","wcb_session_category-palestra"],"jetpack_sharing_enabled":true,"session_date_time":{"date":"29\/11\/2025","time":"15:00"},"session_speakers":[{"id":"2723","slug":"fioravante-souza","name":"Fioravante Souza","link":"https:\/\/brasil.wordcamp.org\/2025\/noticias\/speaker\/fioravante-souza\/"}],"session_cats_rendered":"Palestra","_links":{"self":[{"href":"https:\/\/brasil.wordcamp.org\/2025\/wp-json\/wp\/v2\/sessions\/2803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brasil.wordcamp.org\/2025\/wp-json\/wp\/v2\/sessions"}],"about":[{"href":"https:\/\/brasil.wordcamp.org\/2025\/wp-json\/wp\/v2\/types\/wcb_session"}],"version-history":[{"count":3,"href":"https:\/\/brasil.wordcamp.org\/2025\/wp-json\/wp\/v2\/sessions\/2803\/revisions"}],"predecessor-version":[{"id":3827,"href":"https:\/\/brasil.wordcamp.org\/2025\/wp-json\/wp\/v2\/sessions\/2803\/revisions\/3827"}],"speakers":[{"embeddable":true,"href":"https:\/\/brasil.wordcamp.org\/2025\/wp-json\/wp\/v2\/speakers\/2723"}],"author":[{"embeddable":true,"href":"https:\/\/brasil.wordcamp.org\/2025\/wp-json\/wporg\/v1\/users\/fiocavallari"}],"wp:attachment":[{"href":"https:\/\/brasil.wordcamp.org\/2025\/wp-json\/wp\/v2\/media?parent=2803"}],"wp:term":[{"taxonomy":"wcb_track","embeddable":true,"href":"https:\/\/brasil.wordcamp.org\/2025\/wp-json\/wp\/v2\/session_track?post=2803"},{"taxonomy":"wcb_session_category","embeddable":true,"href":"https:\/\/brasil.wordcamp.org\/2025\/wp-json\/wp\/v2\/session_category?post=2803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}