{"id":2729,"date":"2025-10-27T18:40:37","date_gmt":"2025-10-27T21:40:37","guid":{"rendered":"https:\/\/brasil.wordcamp.org\/2025\/?post_type=wcb_speaker&#038;p=2729"},"modified":"2025-10-27T20:06:32","modified_gmt":"2025-10-27T23:06:32","slug":"carlos-accioly","status":"publish","type":"wcb_speaker","link":"https:\/\/brasil.wordcamp.org\/2025\/noticias\/speaker\/carlos-accioly\/","title":{"rendered":"Carlos Accioly"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Carlos Accioly, com 8 anos de experi\u00eancia como gestor de Ci\u00eancia de Dados em um dos maiores e-commerces da Am\u00e9rica Latina, mostra aos administradores de e-commerce t\u00e9cnicas para aumentar o valor da base de clientes. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os dados transacionais permitem aumentar a frequ\u00eancia de compra e detectar sinais precoces de clientes em risco de churn. O resultado: clientes tratados como indiv\u00edduos \u2014 mais leais, mais rent\u00e1veis e com menor custo de marketing.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carlos Accioly, com 8 anos de experi\u00eancia como gestor de Ci\u00eancia de Dados em um dos maiores e-commerces da Am\u00e9rica Latina, mostra aos administradores de e-commerce t\u00e9cnicas para aumentar o valor da base de clientes. Os dados transacionais permitem aumentar a frequ\u00eancia de compra e detectar sinais precoces de clientes em risco de churn. O [&hellip;]<\/p>\n","protected":false},"author":13917967,"featured_media":2774,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_crdt_document":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_post_was_ever_published":false,"_wcpt_user_name":"","footnotes":""},"speaker_group":[53],"class_list":["post-2729","wcb_speaker","type-wcb_speaker","status-publish","has-post-thumbnail","hentry","wcb_speaker_group-sala-2"],"jetpack_sharing_enabled":true,"avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/d79619cdd52e87d709b14e5a49d5c20aa3107589d1b1c90064d050d8d56108e3?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/d79619cdd52e87d709b14e5a49d5c20aa3107589d1b1c90064d050d8d56108e3?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/d79619cdd52e87d709b14e5a49d5c20aa3107589d1b1c90064d050d8d56108e3?s=96&d=mm&r=g","128":"https:\/\/secure.gravatar.com\/avatar\/d79619cdd52e87d709b14e5a49d5c20aa3107589d1b1c90064d050d8d56108e3?s=128&d=mm&r=g","256":"https:\/\/secure.gravatar.com\/avatar\/d79619cdd52e87d709b14e5a49d5c20aa3107589d1b1c90064d050d8d56108e3?s=256&d=mm&r=g","512":"https:\/\/secure.gravatar.com\/avatar\/d79619cdd52e87d709b14e5a49d5c20aa3107589d1b1c90064d050d8d56108e3?s=512&d=mm&r=g"},"_links":{"self":[{"href":"https:\/\/brasil.wordcamp.org\/2025\/wp-json\/wp\/v2\/speakers\/2729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brasil.wordcamp.org\/2025\/wp-json\/wp\/v2\/speakers"}],"about":[{"href":"https:\/\/brasil.wordcamp.org\/2025\/wp-json\/wp\/v2\/types\/wcb_speaker"}],"author":[{"embeddable":true,"href":"https:\/\/brasil.wordcamp.org\/2025\/wp-json\/wp\/v2\/users\/13917967"}],"replies":[{"embeddable":true,"href":"https:\/\/brasil.wordcamp.org\/2025\/wp-json\/wp\/v2\/comments?post=2729"}],"version-history":[{"count":2,"href":"https:\/\/brasil.wordcamp.org\/2025\/wp-json\/wp\/v2\/speakers\/2729\/revisions"}],"predecessor-version":[{"id":2765,"href":"https:\/\/brasil.wordcamp.org\/2025\/wp-json\/wp\/v2\/speakers\/2729\/revisions\/2765"}],"sessions":[{"embeddable":true,"href":"https:\/\/brasil.wordcamp.org\/2025\/wp-json\/wp\/v2\/sessions\/2797?_embed=1&context=view"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/brasil.wordcamp.org\/2025\/wp-json\/wp\/v2\/media\/2774"}],"wp:attachment":[{"href":"https:\/\/brasil.wordcamp.org\/2025\/wp-json\/wp\/v2\/media?parent=2729"}],"wp:term":[{"taxonomy":"wcb_speaker_group","embeddable":true,"href":"https:\/\/brasil.wordcamp.org\/2025\/wp-json\/wp\/v2\/speaker_group?post=2729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}